{"id":1,"count":5,"description":"","link":"https:\/\/fundibio.com.br\/en\/category\/uncategorized\/","name":"Uncategorized","slug":"uncategorized","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fundibio | Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias<\/title>\n<meta name=\"description\" content=\"A Fundibio \u00e9 a funda\u00e7\u00e3o de apoio vinculada \u00e0 UNESP, dedicada a promover o desenvolvimento cient\u00edfico, a pesquisa e a extens\u00e3o. Conhe\u00e7a nossos projetos, eventos e servi\u00e7os.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fundibio.com.br\/en\/category\/uncategorized\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundibio | Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias\" \/>\n<meta property=\"og:description\" content=\"A Fundibio \u00e9 a funda\u00e7\u00e3o de apoio vinculada \u00e0 UNESP, dedicada a promover o desenvolvimento cient\u00edfico, a pesquisa e a extens\u00e3o. Conhe\u00e7a nossos projetos, eventos e servi\u00e7os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fundibio.com.br\/en\/category\/uncategorized\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundibio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fundibio.com.br\\\/category\\\/uncategorized\\\/\",\"url\":\"https:\\\/\\\/fundibio.com.br\\\/category\\\/uncategorized\\\/\",\"name\":\"Fundibio | Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fundibio.com.br\\\/#website\"},\"description\":\"A Fundibio \u00e9 a funda\u00e7\u00e3o de apoio vinculada \u00e0 UNESP, dedicada a promover o desenvolvimento cient\u00edfico, a pesquisa e a extens\u00e3o. Conhe\u00e7a nossos projetos, eventos e servi\u00e7os.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fundibio.com.br\\\/category\\\/uncategorized\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fundibio.com.br\\\/category\\\/uncategorized\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/fundibio.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fundibio.com.br\\\/#website\",\"url\":\"https:\\\/\\\/fundibio.com.br\\\/\",\"name\":\"Fundibio\",\"description\":\"A Fundibio \u00e9 uma funda\u00e7\u00e3o privada e sem fins lucrativos institu\u00edda pela UNESP. Viabilizamos e gerenciamos projetos de pesquisa e extens\u00e3o\",\"publisher\":{\"@id\":\"https:\\\/\\\/fundibio.com.br\\\/#organization\"},\"alternateName\":\"Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fundibio.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fundibio.com.br\\\/#organization\",\"name\":\"Fundibio\",\"alternateName\":\"Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias\",\"url\":\"https:\\\/\\\/fundibio.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fundibio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Fundibio\"},\"image\":{\"@id\":\"https:\\\/\\\/fundibio.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fundibio\\\/\",\"https:\\\/\\\/www.instagram.com\\\/fundibio\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundibio | Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias","description":"A Fundibio \u00e9 a funda\u00e7\u00e3o de apoio vinculada \u00e0 UNESP, dedicada a promover o desenvolvimento cient\u00edfico, a pesquisa e a extens\u00e3o. Conhe\u00e7a nossos projetos, eventos e servi\u00e7os.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fundibio.com.br\/en\/category\/uncategorized\/","og_locale":"en_US","og_type":"article","og_title":"Fundibio | Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias","og_description":"A Fundibio \u00e9 a funda\u00e7\u00e3o de apoio vinculada \u00e0 UNESP, dedicada a promover o desenvolvimento cient\u00edfico, a pesquisa e a extens\u00e3o. Conhe\u00e7a nossos projetos, eventos e servi\u00e7os.","og_url":"https:\/\/fundibio.com.br\/en\/category\/uncategorized\/","og_site_name":"Fundibio","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fundibio.com.br\/category\/uncategorized\/","url":"https:\/\/fundibio.com.br\/category\/uncategorized\/","name":"Fundibio | Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias","isPartOf":{"@id":"https:\/\/fundibio.com.br\/#website"},"description":"A Fundibio \u00e9 a funda\u00e7\u00e3o de apoio vinculada \u00e0 UNESP, dedicada a promover o desenvolvimento cient\u00edfico, a pesquisa e a extens\u00e3o. Conhe\u00e7a nossos projetos, eventos e servi\u00e7os.","breadcrumb":{"@id":"https:\/\/fundibio.com.br\/category\/uncategorized\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/fundibio.com.br\/category\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/fundibio.com.br\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/fundibio.com.br\/#website","url":"https:\/\/fundibio.com.br\/","name":"Fundibio","description":"A Fundibio \u00e9 uma funda\u00e7\u00e3o privada e sem fins lucrativos institu\u00edda pela UNESP. Viabilizamos e gerenciamos projetos de pesquisa e extens\u00e3o","publisher":{"@id":"https:\/\/fundibio.com.br\/#organization"},"alternateName":"Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fundibio.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fundibio.com.br\/#organization","name":"Fundibio","alternateName":"Funda\u00e7\u00e3o do Instituto de Bioci\u00eancias","url":"https:\/\/fundibio.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fundibio.com.br\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Fundibio"},"image":{"@id":"https:\/\/fundibio.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fundibio\/","https:\/\/www.instagram.com\/fundibio\/"]}]}},"_links":{"self":[{"href":"https:\/\/fundibio.com.br\/en\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fundibio.com.br\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/fundibio.com.br\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/fundibio.com.br\/en\/wp-json\/wp\/v2\/posts?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}